{"id":457,"date":"2019-11-28T12:46:00","date_gmt":"2019-11-28T11:46:00","guid":{"rendered":"https:\/\/www.patrimundi1869.com\/?p=457"},"modified":"2020-02-17T12:52:46","modified_gmt":"2020-02-17T11:52:46","slug":"la-fin-dun-age-dor","status":"publish","type":"post","link":"https:\/\/www.patrimundi1869.com\/en\/2019\/11\/28\/la-fin-dun-age-dor\/","title":{"rendered":"La fin d\u2019un \u00e2ge d\u2019or"},"content":{"rendered":"<p>C\u2019est une petite r\u00e9volution pour le placement pr\u00e9f\u00e9r\u00e9 des fran\u00e7ais : dans une interview aux Echos fin septembre, le PDG de Generali France a jet\u00e9 un pav\u00e9 dans la marre en annon\u00e7ant la fin du \u00ab fonds euro roi \u00bb.<\/p>\n<p>Barri\u00e8res \u00e0 l\u2019entr\u00e9e pour limiter les souscriptions, obligation d\u2019investir un minimum de 60% en unit\u00e9s de compte pour les nouveaux contrats, il s\u2019agit de prot\u00e9ger le rendement des fonds existants et d\u2019adapter la politique commerciale \u00e0 la r\u00e9alit\u00e9 de taux d\u2019int\u00e9r\u00eats plus bas, plus longtemps.<\/p>\n<p>Avec un taux directeur fix\u00e9 par la BCE \u00e0 -0.50% et pr\u00e8s d\u2019un tiers du march\u00e9 obligataire qui offre un rendement n\u00e9gatif, les assureurs ne sont plus en mesure de garantir le triptyque rendement-s\u00e9curit\u00e9-liquidit\u00e9 qui a fait le succ\u00e8s du fonds euro.<\/p>\n<p>Au moment o\u00f9 plusieurs dispositions de la loi PACTE dont la fiscalit\u00e9 visent \u00e0 \u00abrelancer l\u2019actionnariat individuel\u00bb, les fran\u00e7ais sont pr\u00e9venus\u00a0: ils vont devoir prendre un peu plus de risque s\u2019ils veulent du rendement au cours des prochaines ann\u00e9es\u2026<br \/><!--StartFragment--><\/p>\n\n\n<p style=\"color:#af7839\" class=\"has-text-color\"><em>Chronique parue dans le magazine Valeurs Actuelles &#8211; novembre 2019<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C\u2019est une petite r\u00e9volution pour le placement pr\u00e9f\u00e9r\u00e9 des fran\u00e7ais : dans une interview aux Echos fin septembre, le PDG de Generali France a jet\u00e9 un pav\u00e9 dans la marre en annon\u00e7ant la fin du \u00ab fonds euro roi \u00bb. Barri\u00e8res \u00e0 l\u2019entr\u00e9e pour limiter les souscriptions, obligation d\u2019investir un minimum de 60% en unit\u00e9s &hellip;<\/p>\n","protected":false},"author":1,"featured_media":279,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-457","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-release"],"_links":{"self":[{"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/posts\/457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/comments?post=457"}],"version-history":[{"count":2,"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/posts\/457\/revisions"}],"predecessor-version":[{"id":459,"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/posts\/457\/revisions\/459"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/media\/279"}],"wp:attachment":[{"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/media?parent=457"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/categories?post=457"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/en\/wp-json\/wp\/v2\/tags?post=457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}