{"id":506,"date":"2021-05-28T18:50:00","date_gmt":"2021-05-28T16:50:00","guid":{"rendered":"https:\/\/www.patrimundi1869.com\/?p=506"},"modified":"2021-06-29T18:54:07","modified_gmt":"2021-06-29T16:54:07","slug":"derriere-la-crypto-mania","status":"publish","type":"post","link":"https:\/\/www.patrimundi1869.com\/de\/2021\/05\/28\/derriere-la-crypto-mania\/","title":{"rendered":"Derri\u00e8re la Crypto-mania"},"content":{"rendered":"\n<p>Au-del\u00e0 du bitcoin et autres bidules-coin dont les cours \u00e9voluent au gr\u00e9 des tweets de Mr Musk, l\u2019usage de la blockchain prend de l\u2019ampleur et gagne en cr\u00e9dibilit\u00e9. Outre les innovations qui en d\u00e9coulent dans le monde de l\u2019entreprise, les Etats aussi se saisissent du sujet. <\/p>\n\n\n\n<p>Alors que la Chine a officiellement lanc\u00e9 le test de son yuan num\u00e9rique, nous apprenons que la Banque Europ\u00e9enne d\u2019Investissement a \u00e9mis le 27 avril dernier 100 millions d\u2019euros d\u2019obligations num\u00e9riques dont l\u2019enregistrement et le r\u00e8glement s\u2019est effectu\u00e9 gr\u00e2ce \u00e0 la technologie blockchain. Une premi\u00e8re qui s\u2019inscrit dans le cadre des travaux de la BCE sur la cr\u00e9ation d\u2019un euro digital. <\/p>\n\n\n\n<p>Alors faut-il y voir la promesse originelle d\u2019un monde plus fluide, d\u00e9centralis\u00e9, ou la fin annonc\u00e9e de toute forme de confidentialit\u00e9 et le tra\u00e7age syst\u00e9matique de nos d\u00e9penses ? Plus largement, cette technologie r\u00e9put\u00e9e tr\u00e8s \u00e9nergivore va devoir progresser et justifier de r\u00e9els avantages pour survivre aux enjeux \u00e9cologiques actuels\u2026<\/p>\n\n\n\n<p class=\"has-text-color\" style=\"color:#af7938\"><em>Chronique parue dans le magazine Valeurs Actuelles &#8211; mai 2021<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au-del\u00e0 du bitcoin et autres bidules-coin dont les cours \u00e9voluent au gr\u00e9 des tweets de Mr Musk, l\u2019usage de la blockchain prend de l\u2019ampleur et gagne en cr\u00e9dibilit\u00e9. Outre les innovations qui en d\u00e9coulent dans le monde de l\u2019entreprise, les Etats aussi se saisissent du sujet. Alors que la Chine a officiellement lanc\u00e9 le test &hellip;<\/p>\n","protected":false},"author":1,"featured_media":279,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-506","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-release"],"_links":{"self":[{"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/posts\/506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/comments?post=506"}],"version-history":[{"count":2,"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/posts\/506\/revisions"}],"predecessor-version":[{"id":510,"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/posts\/506\/revisions\/510"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/media\/279"}],"wp:attachment":[{"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/media?parent=506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/categories?post=506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.patrimundi1869.com\/de\/wp-json\/wp\/v2\/tags?post=506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}